{"id":156,"date":"2018-10-30T15:39:23","date_gmt":"2018-10-30T15:39:23","guid":{"rendered":"https:\/\/schreinerei-jg.de\/?page_id=156"},"modified":"2019-05-17T13:20:04","modified_gmt":"2019-05-17T13:20:04","slug":"partner","status":"publish","type":"page","link":"https:\/\/www.schreinerei-jg.de\/index.php\/partner\/","title":{"rendered":"Partner"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><a href=\"https:\/\/www.kneer-suedfenster.de\/\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/schreinerei-jg.de\/wp-content\/uploads\/2018\/10\/Logo_Kneer-S\u00fcdfenster.jpg\" alt=\"\" class=\"wp-image-163\" width=\"246\" height=\"128\" srcset=\"https:\/\/www.schreinerei-jg.de\/wp-content\/uploads\/2018\/10\/Logo_Kneer-S\u00fcdfenster.jpg 2493w, https:\/\/www.schreinerei-jg.de\/wp-content\/uploads\/2018\/10\/Logo_Kneer-S\u00fcdfenster-300x157.jpg 300w, https:\/\/www.schreinerei-jg.de\/wp-content\/uploads\/2018\/10\/Logo_Kneer-S\u00fcdfenster-768x401.jpg 768w, https:\/\/www.schreinerei-jg.de\/wp-content\/uploads\/2018\/10\/Logo_Kneer-S\u00fcdfenster-1024x535.jpg 1024w\" sizes=\"auto, (max-width: 246px) 100vw, 246px\" \/><\/a><figcaption><strong>Kneer-S\u00fcd Fenster<\/strong><br><br><\/figcaption><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><a href=\"https:\/\/konold.com\/\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/schreinerei-jg.de\/wp-content\/uploads\/2018\/10\/Logo-Konold-3.png\" alt=\"\" class=\"wp-image-167\" width=\"206\" height=\"114\" srcset=\"https:\/\/www.schreinerei-jg.de\/wp-content\/uploads\/2018\/10\/Logo-Konold-3.png 302w, https:\/\/www.schreinerei-jg.de\/wp-content\/uploads\/2018\/10\/Logo-Konold-3-300x166.png 300w\" sizes=\"auto, (max-width: 206px) 100vw, 206px\" \/><\/a><figcaption><strong>Konold<\/strong><br><\/figcaption><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/schreinerei-jg.de\/wp-content\/uploads\/2018\/10\/B-K.png\" alt=\"\" class=\"wp-image-171\" width=\"214\" height=\"95\"\/><figcaption><strong>Br\u00fcchert + K\u00e4rner<\/strong><\/figcaption><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"215\" height=\"143\" src=\"https:\/\/schreinerei-jg.de\/wp-content\/uploads\/2018\/10\/Illbruck-2.jpg\" alt=\"\" class=\"wp-image-179\"\/><figcaption><strong>Tremco-Illbruck<\/strong><\/figcaption><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/schreinerei-jg.de\/wp-content\/uploads\/2018\/10\/W\u00fcrth.png\" alt=\"\" class=\"wp-image-181\" width=\"199\" height=\"42\" srcset=\"https:\/\/www.schreinerei-jg.de\/wp-content\/uploads\/2018\/10\/W\u00fcrth.png 488w, https:\/\/www.schreinerei-jg.de\/wp-content\/uploads\/2018\/10\/W\u00fcrth-300x63.png 300w\" sizes=\"auto, (max-width: 199px) 100vw, 199px\" \/><figcaption><strong>W\u00fcrth<\/strong><\/figcaption><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/schreinerei-jg.de\/wp-content\/uploads\/2018\/10\/Logo-Neher.jpg\" alt=\"\" class=\"wp-image-164\" width=\"164\" height=\"164\" srcset=\"https:\/\/www.schreinerei-jg.de\/wp-content\/uploads\/2018\/10\/Logo-Neher.jpg 5236w, https:\/\/www.schreinerei-jg.de\/wp-content\/uploads\/2018\/10\/Logo-Neher-150x150.jpg 150w, https:\/\/www.schreinerei-jg.de\/wp-content\/uploads\/2018\/10\/Logo-Neher-300x300.jpg 300w, https:\/\/www.schreinerei-jg.de\/wp-content\/uploads\/2018\/10\/Logo-Neher-768x768.jpg 768w, https:\/\/www.schreinerei-jg.de\/wp-content\/uploads\/2018\/10\/Logo-Neher-1024x1024.jpg 1024w\" sizes=\"auto, (max-width: 164px) 100vw, 164px\" \/><figcaption><strong>Die Muggergittermacher<\/strong><\/figcaption><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"ngg_post_thumbnail":0,"footnotes":""},"class_list":["post-156","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.schreinerei-jg.de\/index.php\/wp-json\/wp\/v2\/pages\/156","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.schreinerei-jg.de\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.schreinerei-jg.de\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.schreinerei-jg.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.schreinerei-jg.de\/index.php\/wp-json\/wp\/v2\/comments?post=156"}],"version-history":[{"count":12,"href":"https:\/\/www.schreinerei-jg.de\/index.php\/wp-json\/wp\/v2\/pages\/156\/revisions"}],"predecessor-version":[{"id":224,"href":"https:\/\/www.schreinerei-jg.de\/index.php\/wp-json\/wp\/v2\/pages\/156\/revisions\/224"}],"wp:attachment":[{"href":"https:\/\/www.schreinerei-jg.de\/index.php\/wp-json\/wp\/v2\/media?parent=156"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}